{"id":30421,"date":"2021-07-07T11:50:52","date_gmt":"2021-07-07T09:50:52","guid":{"rendered":"https:\/\/musee.oceano.org\/datenschutz-rgpd\/"},"modified":"2021-07-07T11:51:18","modified_gmt":"2021-07-07T09:51:18","slug":"datenschutz-rgpd","status":"publish","type":"page","link":"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/","title":{"rendered":"Datenschutz \/ RGPD"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"30421\" class=\"elementor elementor-30421 elementor-4847\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-117832aa elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"117832aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e90c5e9\" data-id=\"e90c5e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a5eacf9 elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"1a5eacf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-891be05 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"u2151\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><h1 class=\"elementor-slide-heading\">Datenschutz RGPD<\/h1><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47bbdfe3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"47bbdfe3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebf7cf0\" data-id=\"ebf7cf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1839d7dd elementor-widget elementor-widget-ee-breadcrumbs\" data-id=\"1839d7dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ee-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"ee-breadcrumbs\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/BreadcrumbList\"><\/ul>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cd1134a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cd1134a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-275ee04f\" data-id=\"275ee04f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42d4e778 elementor-widget elementor-widget-heading\" data-id=\"42d4e778\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datenschutzbestimmungen :<br>Die Verpflichtungen des \"Ozeanographischen Instituts - Stiftung Albert I., F\u00fcrst von Monaco<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6214021 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6214021\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed226be\" data-id=\"ed226be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4346539 elementor-widget elementor-widget-heading\" data-id=\"4346539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datenerfassung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15fd502d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15fd502d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4895c3f3\" data-id=\"4895c3f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37663506 elementor-widget elementor-widget-text-editor\" data-id=\"37663506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das &#8222;<strong>Ozeanographische Institut &#8211; Stiftung Albert I., F\u00fcrst von Monaco&#8220;<\/strong> ist bestrebt, die Privatsph\u00e4re zu respektieren und die Informationen, ob pers\u00f6nlich oder nicht, aller Internetnutzer zu sch\u00fctzen, die auf die Website des &#8222;Ozeanographischen Instituts &#8211; Stiftung Albert I., F\u00fcrst von Monaco&#8220; zugreifen m\u00f6chten. Die in deklaratorischer Form mitgeteilten Informationen sind f\u00fcr das &#8222;Institut Oc\u00e9anographique &#8211; Fondation Albert Ier, Prince de Monaco&#8220; bestimmt und werden nur f\u00fcr den alleinigen Zweck der Datenerhebung in \u00dcbereinstimmung mit den geltenden Gesetzen und Vorschriften und insbesondere der Allgemeinen Datenschutzverordnung verwendet.<\/p>\n<p><strong>&#8220; Das Ozeanographische Institut &#8211; Stiftung Albert I., F\u00fcrst von Monaco<\/strong>  verpflichtet sich au\u00dferdem, diese Informationen nicht an Dritte weiterzugeben, d.h. an Organisationen oder Unternehmen au\u00dferhalb der Gruppe oder an Einzelpersonen zu Zwecken, die nicht im Zusammenhang mit den T\u00e4tigkeitsbereichen des &#8222;Institut Oc\u00e9anographique &#8211; Fondation Albert Ier, Prince de Monaco&#8220; stehen.<\/p>\n<p>Im Interesse der Transparenz und des Schutzes der Rechte erh\u00e4lt das &#8222;Institut Oc\u00e9anographique &#8211; Fondation Albert Ier, Prince of Monaco&#8220; keine Informationen, die einen Benutzer pers\u00f6nlich identifizieren k\u00f6nnten, mit Ausnahme derjenigen, die durch das Ausf\u00fcllen und Absenden der Formulare auf der Website mitgeteilt werden.  <br \/>Die gesammelten Informationen sind notwendig, um auf Informationsanfragen zu antworten und um informative E-Mails zu versenden. Sie sind ausschlie\u00dflich f\u00fcr &#8222;The Oceanographic Institute &#8211; Albert I, Prince of Monaco Foundation&#8220; bestimmt.<\/p>\n<p>Eine kommerzielle Nutzung der gesammelten Daten, auch in Teilen, ist nicht vorgesehen. Diese Informationen sind vertraulich und werden vom &#8222;Institut Oc\u00e9anographique &#8211; Fondation Albert Ier, Prince de Monaco&#8220; aufbewahrt.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3035647 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3035647\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d09cae\" data-id=\"6d09cae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4466623 elementor-widget elementor-widget-heading\" data-id=\"4466623\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nicht-personenbezogene Daten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9a68b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9a68b0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc82d79\" data-id=\"dc82d79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22241e4 elementor-widget elementor-widget-text-editor\" data-id=\"22241e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die bereitgestellten nicht-personenbezogenen Informationen werden verwendet, um Produkte anzubieten, die auf den Geschmack der Benutzer zugeschnitten sind. Das &#8222;Institut Oc\u00e9anographique &#8211; Fondation Albert I., Prince of Monaco&#8220; wird wahrscheinlich automatisch Informationen erhalten, die aber unter keinen Umst\u00e4nden einer Person zugeordnet werden k\u00f6nnen. Zu diesen Informationen geh\u00f6ren der Typ des verwendeten Internet-Browsers, das Betriebssystem des Computers und der Name der Domain, von der aus auf unsere Seite zugegriffen wurde.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-179a206 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"179a206\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8fa4195\" data-id=\"8fa4195\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d3cdf4 elementor-widget elementor-widget-heading\" data-id=\"3d3cdf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zugriffs- und \u00c4nderungsrecht  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2a14cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2a14cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13a5b31\" data-id=\"13a5b31\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3296f10 elementor-widget elementor-widget-text-editor\" data-id=\"3296f10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gem\u00e4\u00df Artikel 14 des monegassischen Gesetzes vom 23. Dezember 1993 haben Sie das Recht auf Zugang und Berichtigung der Sie betreffenden pers\u00f6nlichen Daten. Sie k\u00f6nnen der Weitergabe der von Ihnen angegebenen Daten jederzeit unentgeltlich und ohne Angabe von Gr\u00fcnden widersprechen.<\/p>\n<p><strong>F\u00fcr jede Kontaktaufnahme bez\u00fcglich Ihrer pers\u00f6nlichen Daten:<\/strong><\/p>\n<p>Das Ozeanographische Institut &#8211; Stiftung Albert I., F\u00fcrst von Monaco<br \/>Avenue Saint-Martin<br \/>MC 98000 Monaco<br \/>Tel: + 377 93 15 36 00<br \/>Fax: + 377 93 50 52 97<br \/>E-Mail : <u><br \/>\n  <a href=\"mailto:musee@oceano.mc\">musee@oceano.mc<\/a><br \/>\n<\/u><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8344e2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c8344e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1114341\" data-id=\"1114341\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e8b412 elementor-widget elementor-widget-heading\" data-id=\"4e8b412\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cookie-Richtlinie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e60c58 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e60c58\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13f552a\" data-id=\"13f552a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbd94bc elementor-widget elementor-widget-text-editor\" data-id=\"cbd94bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Sie unsere Website besuchen, k\u00f6nnen Cookies auf Ihrem Computer abgelegt werden. Ein Cookie identifiziert eine Person nicht. Im Allgemeinen speichert es Informationen, die sich auf die Navigation des Computers auf unserer Website beziehen (die konsultierten Seiten, das Datum und die Uhrzeit der Konsultation, usw.) und die bei sp\u00e4teren Besuchen gelesen werden.<\/p>\n<p>Ein &#8222;Cookie&#8220; ist eine Datei, die von Ihrem Browser auf Ihrem Computer abgelegt wird.  <br \/>Cookies werden verwendet, um permanente oder tempor\u00e4re Informationen zu speichern.  <br \/>Hier sind die Informationen, die in dem Cookie auf Ihrem Computer gespeichert werden:<\/p>\n<ul>\n<li>Allgemeine Benutzeridentifikation, eine eindeutige Nummer, mit der gez\u00e4hlt wird, wie oft eine Meldung auf dem Computer angezeigt wird, auf dem sich das Cookie befindet<\/li>\n<li>Der Name der Domain, die das Cookie verteilt<\/li>\n<li>Verfallsdatum<\/li>\n<li>Das Datum der letzten Aktualisierung<\/li>\n<li>http-Spezifikationen: bezieht sich auf Ihr Betriebssystemmodell und Ihren Browser.<\/li>\n<\/ul>\n<p>Sie k\u00f6nnen <strong>die Speicherung von Cookies nat\u00fcrlich verhindern<\/strong>, indem Sie Ihren Browser entsprechend konfigurieren.<\/p>\n<p>Sie k\u00f6nnen Cookies auch jederzeit und einzeln l\u00f6schen, indem Sie die Bedienungsanleitung Ihres Betriebssystems zu Rate ziehen.<\/p>\n<p>Wenn Sie auf unserer Website einen Kommentar oder eine Frage abgeben oder sich in eine Mailingliste eintragen, wird Ihnen die M\u00f6glichkeit geboten, Ihren Namen, Ihre E-Mail-Adresse und Ihre Website in Cookies zu speichern. Dies ist nur zu Ihrer Bequemlichkeit, damit Sie diese Informationen nicht erneut eingeben m\u00fcssen, wenn Sie sp\u00e4ter einen weiteren Kommentar hinterlassen. Diese Cookies verfallen nach einem Jahr.<\/p>\n<p>Wenn Sie ein Konto haben und sich auf dieser Website anmelden, wird ein tempor\u00e4rer Cookie gesetzt, um festzustellen, ob Ihr Browser Cookies akzeptiert. Sie enth\u00e4lt keine pers\u00f6nlichen Daten und wird automatisch gel\u00f6scht, wenn Sie Ihren Browser schlie\u00dfen.<\/p>\n<p>Wenn Sie sich anmelden, werden wir eine Reihe von Cookies setzen, um Ihre Anmeldeinformationen und Bildschirmeinstellungen zu speichern. Die Lebensdauer eines Verbindungs-Cookies betr\u00e4gt zwei Tage, die eines Bildschirmoptions-Cookies ein Jahr. Wenn Sie &#8222;Remember me&#8220; ankreuzen, wird Ihr Login-Cookie zwei Wochen lang aufbewahrt. Wenn Sie sich von Ihrem Konto abmelden, wird das Anmelde-Cookie gel\u00f6scht.<\/p>\n<p>Wenn Sie einen Artikel bearbeiten oder ver\u00f6ffentlichen, wird ein zus\u00e4tzliches Cookie in Ihrem Browser gespeichert. Dieses Cookie enth\u00e4lt keine pers\u00f6nlichen Daten. Sie gibt einfach die ID des Elements an, das Sie gerade ge\u00e4ndert haben. Er verf\u00e4llt nach einem Tag.<\/p>\n<p>Die von den Cookies m\u00f6glicherweise erfasste IP-Adresse wird automatisch anonymisiert, bevor sie in Google Analytics aufgenommen wird, um eine weitere Nutzung dieser personenbezogenen Daten oder einen Abgleich mit anderen personenbezogenen Daten zu vermeiden;<\/p>\n<p>Schlie\u00dflich werden die anonymisierten Cookie-Informationen f\u00fcr einen Zeitraum von 13 Monaten aufbewahrt.<\/p>\n<p>Sie k\u00f6nnen festlegen, welche Cookies Sie zulassen oder nicht zulassen m\u00f6chten, indem Sie auf die folgende Schaltfl\u00e4che klicken.<\/p>\n<p><a href=\"#\">Anpassen Ihrer Cookies<\/a><\/p>\n<p>Wenn Sie Fragen zu Ihren pers\u00f6nlichen Daten haben, k\u00f6nnen Sie sich per E-Mail an die folgende Adresse wenden: <a href=\"mailto:infos.nominatives@oceano.org\">infos.nominatives@oceano.org<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3db0c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3db0c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c3e805d\" data-id=\"c3e805d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a8889f elementor-widget elementor-widget-heading\" data-id=\"8a8889f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anwendbares Recht<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5b18a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5b18a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fd6fc54\" data-id=\"fd6fc54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5979b80 elementor-widget elementor-widget-text-editor\" data-id=\"5979b80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Im Falle von Streitigkeiten sind ausschlie\u00dflich die monegassischen Gerichte zust\u00e4ndig.  <br \/>Jeder Nutzer dieser Website und durch diese alleinige Nutzung wird davon ausgegangen, dass er die Anwendung des Gesetzes und die ausschlie\u00dfliche Zust\u00e4ndigkeit der monegassischen Gerichte f\u00fcr alle Handlungen akzeptiert, die er im Zusammenhang mit diesen &#8222;Nutzungsbedingungen&#8220; oder der Nutzung dieser Website unternimmt.  <br \/>Diese &#8222;Nutzungsbedingungen&#8220; gelten vorbehaltlich aller zwingenden Bestimmungen des monegassischen Rechts, die m\u00f6glicherweise anwendbar sind.  <br \/>Wenn Sie Fragen oder Beschwerden haben, wenden Sie sich bitte per E-Mail an uns:  <u><\/u><u><br \/>\n  <a href=\"mailto:musee@oceano.mc\">musee@oceano.mc<\/a><br \/>\n<\/u> .<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Datenschutz RGPD Datenschutzbestimmungen :Die Verpflichtungen des &#8222;Ozeanographischen Instituts &#8211; Stiftung Albert I., F\u00fcrst von Monaco Datenerfassung Das &#8222;Ozeanographische Institut &#8211; Stiftung Albert I., F\u00fcrst von Monaco&#8220; ist bestrebt, die Privatsph\u00e4re zu respektieren und die Informationen, ob pers\u00f6nlich oder nicht, aller Internetnutzer zu sch\u00fctzen, die auf die Website des &#8222;Ozeanographischen Instituts &#8211; Stiftung Albert I., F\u00fcrst [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-30421","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz \/ RGPD - Mus\u00e9e Oc\u00e9anographique de Monaco<\/title>\n<meta name=\"description\" content=\"Siehe unsere Richtlinien zum Datenschutz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz \/ RGPD - Mus\u00e9e Oc\u00e9anographique de Monaco\" \/>\n<meta property=\"og:description\" content=\"Siehe unsere Richtlinien zum Datenschutz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/\" \/>\n<meta property=\"og:site_name\" content=\"Mus\u00e9e Oc\u00e9anographique de Monaco\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-07T09:51:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/\",\"url\":\"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/\",\"name\":\"Datenschutz \/ RGPD - Mus\u00e9e Oc\u00e9anographique de Monaco\",\"isPartOf\":{\"@id\":\"https:\/\/musee.oceano.org\/#website\"},\"datePublished\":\"2021-07-07T09:50:52+00:00\",\"dateModified\":\"2021-07-07T09:51:18+00:00\",\"description\":\"Siehe unsere Richtlinien zum Datenschutz.\",\"breadcrumb\":{\"@id\":\"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/musee.oceano.org\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz \/ RGPD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/musee.oceano.org\/#website\",\"url\":\"https:\/\/musee.oceano.org\/\",\"name\":\"Mus\u00e9e Oc\u00e9anographique de Monaco\",\"description\":\"Faire conna\u00eetre, aimer et prot\u00e9ger les oc\u00e9ans\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/musee.oceano.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz \/ RGPD - Mus\u00e9e Oc\u00e9anographique de Monaco","description":"Siehe unsere Richtlinien zum Datenschutz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutz \/ RGPD - Mus\u00e9e Oc\u00e9anographique de Monaco","og_description":"Siehe unsere Richtlinien zum Datenschutz.","og_url":"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/","og_site_name":"Mus\u00e9e Oc\u00e9anographique de Monaco","article_modified_time":"2021-07-07T09:51:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/","url":"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/","name":"Datenschutz \/ RGPD - Mus\u00e9e Oc\u00e9anographique de Monaco","isPartOf":{"@id":"https:\/\/musee.oceano.org\/#website"},"datePublished":"2021-07-07T09:50:52+00:00","dateModified":"2021-07-07T09:51:18+00:00","description":"Siehe unsere Richtlinien zum Datenschutz.","breadcrumb":{"@id":"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/musee.oceano.org\/de\/datenschutz-rgpd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/musee.oceano.org\/de\/"},{"@type":"ListItem","position":2,"name":"Datenschutz \/ RGPD"}]},{"@type":"WebSite","@id":"https:\/\/musee.oceano.org\/#website","url":"https:\/\/musee.oceano.org\/","name":"Mus\u00e9e Oc\u00e9anographique de Monaco","description":"Faire conna\u00eetre, aimer et prot\u00e9ger les oc\u00e9ans","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musee.oceano.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/musee.oceano.org\/de\/wp-json\/wp\/v2\/pages\/30421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musee.oceano.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/musee.oceano.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/musee.oceano.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/musee.oceano.org\/de\/wp-json\/wp\/v2\/comments?post=30421"}],"version-history":[{"count":3,"href":"https:\/\/musee.oceano.org\/de\/wp-json\/wp\/v2\/pages\/30421\/revisions"}],"predecessor-version":[{"id":30436,"href":"https:\/\/musee.oceano.org\/de\/wp-json\/wp\/v2\/pages\/30421\/revisions\/30436"}],"wp:attachment":[{"href":"https:\/\/musee.oceano.org\/de\/wp-json\/wp\/v2\/media?parent=30421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}