{"id":25827,"date":"2021-06-25T16:37:47","date_gmt":"2021-06-25T14:37:47","guid":{"rendered":"https:\/\/musee.oceano.org\/expositions\/a-odisseia-da-tartaruga-marinha-a-exposicao\/"},"modified":"2021-07-15T17:53:11","modified_gmt":"2021-07-15T15:53:11","slug":"a-odisseia-da-tartaruga-marinha-a-exposicao","status":"publish","type":"expositions","link":"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/","title":{"rendered":"A Odisseia da Tartaruga Marinha &#8211; A Exposi\u00e7\u00e3o"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"25827\" class=\"elementor elementor-25827 elementor-1517\" data-elementor-post-type=\"expositions\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-154492fe elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"154492fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d62217d\" data-id=\"5d62217d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc2d10e elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"cc2d10e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-891be05 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"De leur cycle de vie aux menaces qui p\u00e8sent sur leur existence, de la magie de la ponte aux actions men\u00e9es pour leur pr\u00e9servation, la grande aventure des tortues marines se raconte au Mus\u00e9e oc\u00e9anographique, dans un tout nouvel espace de 550 m\u00b2. \n\nCe nouvel espace renforce le dialogue avec tous nos publics (visiteurs, chercheurs, d\u00e9cideurs, scolaires) et ouvre un terrain de d\u00e9couverte, de partage et d\u2019engagement en faveur des tortues marines.\n\nUn centre de soins\nLe Centre Mon\u00e9gasque de Soins des Esp\u00e8ces A rescue center Marines (CMSEM) est le coeur de notre nouveau dispositif d\u2019action et de sensibilisation. \nY sont soign\u00e9s grandes nacres, hippocampes\u2026 mais aussi tortues marines.\nLeurs blessures les plus fr\u00e9quentes : prise accidentelle dans des filets, carapace fendue, ingestion de plastique ou d\u2019hame\u00e7on. Habilit\u00e9s \u00e0 manipuler ces esp\u00e8ces prot\u00e9g\u00e9es, nos soigneurs interviennent en collaboration avec des v\u00e9t\u00e9rinaires sp\u00e9cialis\u00e9s et les r\u00e9seaux fran\u00e7ais et ,europ\u00e9ens des centres de soins. L\u2019occasion de contribuer aux programmes d\u2019\u00e9tudes relatifs \u00e0 la biologie de ces esp\u00e8ces, \u00e0 leur comportement et \u00e0 leur environnement.\n\nLa provenance des \u00ab patients \u00bb\nLe CMSEM soigne des tortues recueillies directement en mer, sur le littoral mon\u00e9gasque ou \u00e0 proximit\u00e9. Elles peuvent aussi nous \u00eatre confi\u00e9es par d\u2019autres centres de soins satur\u00e9s au moment de la prise en charge. L&#039;Institut oc\u00e9anographique collabore notamment avec le R\u00e9seau des Tortues Marines de M\u00e9diterran\u00e9e Fran\u00e7aise (RTMMF, g\u00e9r\u00e9 par la Soci\u00e9t\u00e9 Herp\u00e9tologique de France) et le Centre d\u2019Etudes et de Sauvegarde des Tortues de M\u00e9diterran\u00e9e (CESTMed). Tous les usagers de la mer (pouvoirs publics, plaisanciers, plongeurs, p\u00eacheurs\u2026) sont invit\u00e9s \u00e0 nous alerter en cas de rencontre avec un animal marin en d\u00e9tresse.\n\nLe retour en mer\nAvant de retrouver le large, les tortues passent par un bassin de r\u00e9habilitation de 160 m3, situ\u00e9 en plein air, pour s\u2019assurer\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><h1 class=\"elementor-slide-heading\">A Odisseia da Tartaruga: A Exposi\u00e7\u00e3o<\/h1><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41571b57 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"41571b57\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b4c1dc\" data-id=\"5b4c1dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea5fdb7 elementor-widget elementor-widget-ee-breadcrumbs\" data-id=\"ea5fdb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ee-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"ee-breadcrumbs\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/BreadcrumbList\"><\/ul>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6911f49 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6911f49\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27e84246\" data-id=\"27e84246\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d1b6eaf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d1b6eaf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-22a31c5f\" data-id=\"22a31c5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-609d646 elementor-zoom elementor-widget elementor-widget-image\" data-id=\"609d646\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"762\" height=\"578\" src=\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/06\/4-Parcours-th\u00e9matique-Odyss\u00e9e-des-tortues-marines-\u00a9-M.-Dagnino-Institut-oc\u00e9anographique-762x578.jpg\" class=\"attachment-img-actu-section size-img-actu-section wp-image-5014\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5988fdb2\" data-id=\"5988fdb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d70cbb7 elementor-widget elementor-widget-text-editor\" data-id=\"3d70cbb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Desde a sua apari\u00e7\u00e3o na Terra, h\u00e1 milh\u00f5es de anos, at\u00e9 \u00e0s amea\u00e7as \u00e0 sua exist\u00eancia, da magia de p\u00f4r ovos \u00e0s a\u00e7\u00f5es tomadas para os preservar, a grande aventura das tartarugas marinhas \u00e9 contada no Museu Oceanogr\u00e1fico na nova exposi\u00e7\u00e3o The Sea Turtle Odyssey.<\/p>\n<p>Ecoando a visita ao novo espa\u00e7o que apresenta as tartarugas do Centro de Cuidados Monegascos, a exposi\u00e7\u00e3o familiariza-nos com a hist\u00f3ria deste fascinante e misterioso animal. Entre outras coisas, permite-nos compreender que, embora estejamos potencialmente no in\u00edcio da sua extin\u00e7\u00e3o devido \u00e0s nossas pr\u00e1ticas di\u00e1rias, tanto individuais como coletivas, cada um de n\u00f3s tamb\u00e9m faz parte da solu\u00e7\u00e3o para a sua conserva\u00e7\u00e3o.<\/p>\n<p>O Instituto Oceanogr\u00e1fico, o Pr\u00edncipe Alberto II da Funda\u00e7\u00e3o M\u00f3naco, as Explora\u00e7\u00f5es do M\u00f3naco e todas as organiza\u00e7\u00f5es parceiras est\u00e3o a mobilizar-se para as tartarugas atrav\u00e9s das suas a\u00e7\u00f5es sem fronteiras, e convidam-no a participar ativamente na sua prote\u00e7\u00e3o.<br \/>Para ver antes do in\u00edcio de janeiro de 2020!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad8930f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad8930f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3fb54bf5\" data-id=\"3fb54bf5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ff1eebb elementor-widget elementor-widget-heading\" data-id=\"6ff1eebb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sobreviventes de dinossauros<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36ca4b95 elementor-widget elementor-widget-text-editor\" data-id=\"36ca4b95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Com 150 milh\u00f5es de anos de exist\u00eancia, as tartarugas marinhas j\u00e1 sobreviveram a uma crise de extin\u00e7\u00e3o em massa que viu o desaparecimento de dinossauros e muitos r\u00e9pteis. Este m\u00f3dulo permite-lhe descobrir os restos de alguns ancestrais das tartarugas marinhas atuais, e em particular a reconstru\u00e7\u00e3o de um f\u00f3ssil de Archelon com 66 milh\u00f5es de anos, medindo 5m por 2m50!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ed8e07 elementor-widget elementor-widget-heading\" data-id=\"4ed8e07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">pequena fam\u00edlia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-532b1c07 elementor-widget elementor-widget-text-editor\" data-id=\"532b1c07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como um dos animais mais antigos do nosso planeta, as tartarugas marinhas passaram milh\u00f5es de anos a adaptarem-se para se tornarem os animais que conhecemos hoje. Apenas sete esp\u00e9cies diferentes de tartarugas marinhas ainda frequentam os nossos oceanos. Desde os leitos de ervas marinhas rasas do Oceano \u00cdndico at\u00e9 aos recifes coloridos do Tri\u00e2ngulo coral, das praias de areia branca do Pac\u00edfico \u00e0s costas mediterr\u00e2nicas, descubra a incr\u00edvel odisseia que estes extraordin\u00e1rios animais ainda experimentam.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30ca02d8 elementor-widget elementor-widget-heading\" data-id=\"30ca02d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Assassinos em S\u00e9rie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-530e364 elementor-widget elementor-widget-text-editor\" data-id=\"530e364\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Depois de sobreviverem a muitos perigos naturais, as tartarugas marinhas s\u00e3o agora amea\u00e7adas pelos seres humanos em todas as fases do seu desenvolvimento, apesar do seu estatuto de esp\u00e9cie protegida. Sem conhecer as fronteiras, a sua formid\u00e1vel odisseia tornou-se um verdadeiro obst\u00e1culo, em terra e no mar. Este m\u00f3dulo olha para os obst\u00e1culos que trufam o seu percurso, como a ocupa\u00e7\u00e3o costeira, a ca\u00e7a furtiva, os impactos da pesca, polui\u00e7\u00e3o, res\u00edduos de pl\u00e1stico&#8230;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f5b36a elementor-widget elementor-widget-heading\" data-id=\"6f5b36a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00f3naco, um rem\u00e9dio para as tartarugas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70e4ecb8 elementor-widget elementor-widget-text-editor\" data-id=\"70e4ecb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sob o impulso do Pr\u00edncipe Alberto II do M\u00f3naco, porta-voz da causa dos oceanos perante organismos internacionais, os atores monegascos est\u00e3o a unir os seus esfor\u00e7os para proteger as tartarugas marinhas&#8230; Descubra atrav\u00e9s desta exposi\u00e7\u00e3o as muitas a\u00e7\u00f5es levadas a cabo pelo Principado para o p\u00fablico em geral, decisores e atores na \u00e1rea.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3612081a\" data-id=\"3612081a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d7d1431 elementor-widget elementor-widget-image\" data-id=\"3d7d1431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"214\" height=\"300\" src=\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/Expo-Odyssee-1-214x300.jpg\" class=\"attachment-medium size-medium wp-image-25842\" alt=\"\" srcset=\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/Expo-Odyssee-1-214x300.jpg 214w, https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/Expo-Odyssee-1-768x1076.jpg 768w, https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/Expo-Odyssee-1-731x1024.jpg 731w, https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/Expo-Odyssee-1.jpg 1098w\" sizes=\"(max-width: 214px) 100vw, 214px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6397230b elementor-widget elementor-widget-heading\" data-id=\"6397230b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A solu\u00e7\u00e3o somos n\u00f3s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-76e1889 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76e1889\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3506f3c\" data-id=\"3506f3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b107a6c elementor-widget elementor-widget-text-editor\" data-id=\"6b107a6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>No Museu \u00e9 agora poss\u00edvel que se comprometa individualmente com as tartarugas de forma original e torne este compromisso p\u00fablico imediatamente!<\/p>\n<p>No final da viagem, quando as amea\u00e7as \u00e0s tartarugas s\u00e3o \u00f3bvias, como o facto de cada um de n\u00f3s fazer parte do problema, convidamos todos a comprometerem-se a tornarem-se parte da solu\u00e7\u00e3o! 6 compromissos para gestos simples do dia-a-dia que participam, de certa forma, num trabalho comum: cada foto tirada comp\u00f5e um mosaico ilustrando uma tartaruga marinha&#8230;<\/p>\n<p>No Instituto Oceanogr\u00e1fico, acreditamos no poder do indiv\u00edduo e no impacto que pode ter nas suas escolhas di\u00e1rias!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b700118 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b700118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/musee.oceano.org\/2019\/06\/24\/engez-vous-avec-nous-pour-les-tortues-marines\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprometam-se!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-359e2f9d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"359e2f9d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ffd83fb\" data-id=\"ffd83fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-227993e4 elementor-widget elementor-widget-heading\" data-id=\"227993e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ver tamb\u00e9m<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e53d85 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e53d85\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-56751ea5 animated-slow elementor-invisible\" data-id=\"56751ea5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-211d51b4 elementor-zoom elementor-widget elementor-widget-image\" data-id=\"211d51b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"334\" height=\"334\" src=\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/Editions_Meduses-334x334.jpg\" class=\"attachment-img-bloc-square size-img-bloc-square wp-image-10043\" alt=\"\" srcset=\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/Editions_Meduses-334x334.jpg 334w, https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/Editions_Meduses-150x150.jpg 150w, https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/Editions_Meduses-433x433.jpg 433w\" sizes=\"(max-width: 334px) 100vw, 334px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-377edaa4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"377edaa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.oceano.org\/pt-pt\/edicoes\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">mergulhar nas nossas edi\u00e7\u00f5es<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-744d1922 animated-slow elementor-invisible\" data-id=\"744d1922\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f10a8c4 elementor-zoom elementor-widget elementor-widget-image\" data-id=\"6f10a8c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"334\" height=\"334\" src=\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/Mapping_Buyle-334x334.jpg\" class=\"attachment-img-bloc-square size-img-bloc-square wp-image-10047\" alt=\"\" srcset=\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/Mapping_Buyle-334x334.jpg 334w, https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/Mapping_Buyle-150x150.jpg 150w, https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/Mapping_Buyle-433x433.jpg 433w\" sizes=\"(max-width: 334px) 100vw, 334px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49c6b5c1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"49c6b5c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.oceano.org\/pt-pt\/monaco-a-voz-do-oceano\/as-exploracoes-do-monaco\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">aprender plUS sobre explora\u00e7\u00f5es m\u00f3naco<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-301319d3 animated-slow elementor-invisible\" data-id=\"301319d3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35e7c50d elementor-zoom elementor-widget elementor-widget-image\" data-id=\"35e7c50d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"334\" height=\"334\" src=\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/1-SAS-Albert-Ier-sur-passerelle-334x334.jpg\" class=\"attachment-img-bloc-square size-img-bloc-square wp-image-10051\" alt=\"\" srcset=\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/1-SAS-Albert-Ier-sur-passerelle-334x334.jpg 334w, https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/1-SAS-Albert-Ier-sur-passerelle-150x150.jpg 150w, https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/08\/1-SAS-Albert-Ier-sur-passerelle-433x433.jpg 433w\" sizes=\"(max-width: 334px) 100vw, 334px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63a6ca29 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"63a6ca29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.oceano.org\/pt-pt\/organizacao\/as-grandes-figuras\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">descobrir as grandes figuras do instituto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A Odisseia da Tartaruga: A Exposi\u00e7\u00e3o Desde a sua apari\u00e7\u00e3o na Terra, h\u00e1 milh\u00f5es de anos, at\u00e9 \u00e0s amea\u00e7as \u00e0 sua exist\u00eancia, da magia de p\u00f4r ovos \u00e0s a\u00e7\u00f5es tomadas para os preservar, a grande aventura das tartarugas marinhas \u00e9 contada no Museu Oceanogr\u00e1fico na nova exposi\u00e7\u00e3o The Sea Turtle Odyssey. Ecoando a visita ao [&hellip;]<\/p>\n","protected":false},"featured_media":25854,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"etatexpositions":[339],"class_list":["post-25827","expositions","type-expositions","status-publish","has-post-thumbnail","hentry","etatexpositions-passadas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Odisseia da Tartaruga Marinha - A Exposi\u00e7\u00e3o - Mus\u00e9e Oc\u00e9anographique de Monaco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Odisseia da Tartaruga Marinha - A Exposi\u00e7\u00e3o - Mus\u00e9e Oc\u00e9anographique de Monaco\" \/>\n<meta property=\"og:description\" content=\"A Odisseia da Tartaruga: A Exposi\u00e7\u00e3o Desde a sua apari\u00e7\u00e3o na Terra, h\u00e1 milh\u00f5es de anos, at\u00e9 \u00e0s amea\u00e7as \u00e0 sua exist\u00eancia, da magia de p\u00f4r ovos \u00e0s a\u00e7\u00f5es tomadas para os preservar, a grande aventura das tartarugas marinhas \u00e9 contada no Museu Oceanogr\u00e1fico na nova exposi\u00e7\u00e3o The Sea Turtle Odyssey. Ecoando a visita ao [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/\" \/>\n<meta property=\"og:site_name\" content=\"Mus\u00e9e Oc\u00e9anographique de Monaco\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-15T15:53:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/4-Parcours-th\u00e9matique-Odyss\u00e9e-des-tortues-marines-\u00a9-M.-Dagnino-Institut-oc\u00e9anographique.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/\",\"url\":\"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/\",\"name\":\"A Odisseia da Tartaruga Marinha - A Exposi\u00e7\u00e3o - Mus\u00e9e Oc\u00e9anographique de Monaco\",\"isPartOf\":{\"@id\":\"https:\/\/musee.oceano.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/4-Parcours-th\u00e9matique-Odyss\u00e9e-des-tortues-marines-\u00a9-M.-Dagnino-Institut-oc\u00e9anographique.jpg\",\"datePublished\":\"2021-06-25T14:37:47+00:00\",\"dateModified\":\"2021-07-15T15:53:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/#primaryimage\",\"url\":\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/4-Parcours-th\u00e9matique-Odyss\u00e9e-des-tortues-marines-\u00a9-M.-Dagnino-Institut-oc\u00e9anographique.jpg\",\"contentUrl\":\"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/4-Parcours-th\u00e9matique-Odyss\u00e9e-des-tortues-marines-\u00a9-M.-Dagnino-Institut-oc\u00e9anographique.jpg\",\"width\":800,\"height\":533,\"caption\":\"De leur cycle de vie aux menaces qui p\u00e8sent sur leur existence, de la magie de la ponte aux actions men\u00e9es pour leur pr\u00e9servation, la grande aventure des tortues marines se raconte au Mus\u00e9e oc\u00e9anographique, dans un tout nouvel espace de 550 m\u00b2. Ce nouvel espace renforce le dialogue avec tous nos publics (visiteurs, chercheurs, d\u00e9cideurs, scolaires) et ouvre un terrain de d\u00e9couverte, de partage et d\u2019engagement en faveur des tortues marines. Un centre de soins Le Centre Mon\u00e9gasque de Soins des Esp\u00e8ces A rescue center Marines (CMSEM) est le coeur de notre nouveau dispositif d\u2019action et de sensibilisation. Y sont soign\u00e9s grandes nacres, hippocampes\u2026 mais aussi tortues marines. Leurs blessures les plus fr\u00e9quentes : prise accidentelle dans des filets, carapace fendue, ingestion de plastique ou d\u2019hame\u00e7on. Habilit\u00e9s \u00e0 manipuler ces esp\u00e8ces prot\u00e9g\u00e9es, nos soigneurs interviennent en collaboration avec des v\u00e9t\u00e9rinaires sp\u00e9cialis\u00e9s et les r\u00e9seaux fran\u00e7ais et ,europ\u00e9ens des centres de soins. L\u2019occasion de contribuer aux programmes d\u2019\u00e9tudes relatifs \u00e0 la biologie de ces esp\u00e8ces, \u00e0 leur comportement et \u00e0 leur environnement. La provenance des \u00ab patients \u00bb Le CMSEM soigne des tortues recueillies directement en mer, sur le littoral mon\u00e9gasque ou \u00e0 proximit\u00e9. Elles peuvent aussi nous \u00eatre confi\u00e9es par d\u2019autres centres de soins satur\u00e9s au moment de la prise en charge. L'Institut oc\u00e9anographique collabore notamment avec le R\u00e9seau des Tortues Marines de M\u00e9diterran\u00e9e Fran\u00e7aise (RTMMF, g\u00e9r\u00e9 par la Soci\u00e9t\u00e9 Herp\u00e9tologique de France) et le Centre d\u2019Etudes et de Sauvegarde des Tortues de M\u00e9diterran\u00e9e (CESTMed). Tous les usagers de la mer (pouvoirs publics, plaisanciers, plongeurs, p\u00eacheurs\u2026) sont invit\u00e9s \u00e0 nous alerter en cas de rencontre avec un animal marin en d\u00e9tresse. Le retour en mer Avant de retrouver le large, les tortues passent par un bassin de r\u00e9habilitation de 160 m3, situ\u00e9 en plein air, pour s\u2019assurer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/musee.oceano.org\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tentoonstellingen\",\"item\":\"https:\/\/musee.oceano.org\/nl\/tentoonstellingen\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A Odisseia da Tartaruga Marinha &#8211; A Exposi\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/musee.oceano.org\/#website\",\"url\":\"https:\/\/musee.oceano.org\/\",\"name\":\"Mus\u00e9e Oc\u00e9anographique de Monaco\",\"description\":\"Faire conna\u00eetre, aimer et prot\u00e9ger les oc\u00e9ans\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/musee.oceano.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Odisseia da Tartaruga Marinha - A Exposi\u00e7\u00e3o - Mus\u00e9e Oc\u00e9anographique de Monaco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/","og_locale":"pt_PT","og_type":"article","og_title":"A Odisseia da Tartaruga Marinha - A Exposi\u00e7\u00e3o - Mus\u00e9e Oc\u00e9anographique de Monaco","og_description":"A Odisseia da Tartaruga: A Exposi\u00e7\u00e3o Desde a sua apari\u00e7\u00e3o na Terra, h\u00e1 milh\u00f5es de anos, at\u00e9 \u00e0s amea\u00e7as \u00e0 sua exist\u00eancia, da magia de p\u00f4r ovos \u00e0s a\u00e7\u00f5es tomadas para os preservar, a grande aventura das tartarugas marinhas \u00e9 contada no Museu Oceanogr\u00e1fico na nova exposi\u00e7\u00e3o The Sea Turtle Odyssey. Ecoando a visita ao [&hellip;]","og_url":"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/","og_site_name":"Mus\u00e9e Oc\u00e9anographique de Monaco","article_modified_time":"2021-07-15T15:53:11+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/4-Parcours-th\u00e9matique-Odyss\u00e9e-des-tortues-marines-\u00a9-M.-Dagnino-Institut-oc\u00e9anographique.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/","url":"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/","name":"A Odisseia da Tartaruga Marinha - A Exposi\u00e7\u00e3o - Mus\u00e9e Oc\u00e9anographique de Monaco","isPartOf":{"@id":"https:\/\/musee.oceano.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/#primaryimage"},"image":{"@id":"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/#primaryimage"},"thumbnailUrl":"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/4-Parcours-th\u00e9matique-Odyss\u00e9e-des-tortues-marines-\u00a9-M.-Dagnino-Institut-oc\u00e9anographique.jpg","datePublished":"2021-06-25T14:37:47+00:00","dateModified":"2021-07-15T15:53:11+00:00","breadcrumb":{"@id":"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/#primaryimage","url":"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/4-Parcours-th\u00e9matique-Odyss\u00e9e-des-tortues-marines-\u00a9-M.-Dagnino-Institut-oc\u00e9anographique.jpg","contentUrl":"https:\/\/musee.oceano.org\/wp-content\/uploads\/sites\/2\/2019\/05\/4-Parcours-th\u00e9matique-Odyss\u00e9e-des-tortues-marines-\u00a9-M.-Dagnino-Institut-oc\u00e9anographique.jpg","width":800,"height":533,"caption":"De leur cycle de vie aux menaces qui p\u00e8sent sur leur existence, de la magie de la ponte aux actions men\u00e9es pour leur pr\u00e9servation, la grande aventure des tortues marines se raconte au Mus\u00e9e oc\u00e9anographique, dans un tout nouvel espace de 550 m\u00b2. Ce nouvel espace renforce le dialogue avec tous nos publics (visiteurs, chercheurs, d\u00e9cideurs, scolaires) et ouvre un terrain de d\u00e9couverte, de partage et d\u2019engagement en faveur des tortues marines. Un centre de soins Le Centre Mon\u00e9gasque de Soins des Esp\u00e8ces A rescue center Marines (CMSEM) est le coeur de notre nouveau dispositif d\u2019action et de sensibilisation. Y sont soign\u00e9s grandes nacres, hippocampes\u2026 mais aussi tortues marines. Leurs blessures les plus fr\u00e9quentes : prise accidentelle dans des filets, carapace fendue, ingestion de plastique ou d\u2019hame\u00e7on. Habilit\u00e9s \u00e0 manipuler ces esp\u00e8ces prot\u00e9g\u00e9es, nos soigneurs interviennent en collaboration avec des v\u00e9t\u00e9rinaires sp\u00e9cialis\u00e9s et les r\u00e9seaux fran\u00e7ais et ,europ\u00e9ens des centres de soins. L\u2019occasion de contribuer aux programmes d\u2019\u00e9tudes relatifs \u00e0 la biologie de ces esp\u00e8ces, \u00e0 leur comportement et \u00e0 leur environnement. La provenance des \u00ab patients \u00bb Le CMSEM soigne des tortues recueillies directement en mer, sur le littoral mon\u00e9gasque ou \u00e0 proximit\u00e9. Elles peuvent aussi nous \u00eatre confi\u00e9es par d\u2019autres centres de soins satur\u00e9s au moment de la prise en charge. L'Institut oc\u00e9anographique collabore notamment avec le R\u00e9seau des Tortues Marines de M\u00e9diterran\u00e9e Fran\u00e7aise (RTMMF, g\u00e9r\u00e9 par la Soci\u00e9t\u00e9 Herp\u00e9tologique de France) et le Centre d\u2019Etudes et de Sauvegarde des Tortues de M\u00e9diterran\u00e9e (CESTMed). Tous les usagers de la mer (pouvoirs publics, plaisanciers, plongeurs, p\u00eacheurs\u2026) sont invit\u00e9s \u00e0 nous alerter en cas de rencontre avec un animal marin en d\u00e9tresse. Le retour en mer Avant de retrouver le large, les tortues passent par un bassin de r\u00e9habilitation de 160 m3, situ\u00e9 en plein air, pour s\u2019assurer"},{"@type":"BreadcrumbList","@id":"https:\/\/musee.oceano.org\/pt-pt\/exposicoes\/a-odisseia-da-tartaruga-marinha-a-exposicao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/musee.oceano.org\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Tentoonstellingen","item":"https:\/\/musee.oceano.org\/nl\/tentoonstellingen\/"},{"@type":"ListItem","position":3,"name":"A Odisseia da Tartaruga Marinha &#8211; A Exposi\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/musee.oceano.org\/#website","url":"https:\/\/musee.oceano.org\/","name":"Mus\u00e9e Oc\u00e9anographique de Monaco","description":"Faire conna\u00eetre, aimer et prot\u00e9ger les oc\u00e9ans","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musee.oceano.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/musee.oceano.org\/pt-pt\/wp-json\/wp\/v2\/expositions\/25827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musee.oceano.org\/pt-pt\/wp-json\/wp\/v2\/expositions"}],"about":[{"href":"https:\/\/musee.oceano.org\/pt-pt\/wp-json\/wp\/v2\/types\/expositions"}],"version-history":[{"count":8,"href":"https:\/\/musee.oceano.org\/pt-pt\/wp-json\/wp\/v2\/expositions\/25827\/revisions"}],"predecessor-version":[{"id":33026,"href":"https:\/\/musee.oceano.org\/pt-pt\/wp-json\/wp\/v2\/expositions\/25827\/revisions\/33026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musee.oceano.org\/pt-pt\/wp-json\/wp\/v2\/media\/25854"}],"wp:attachment":[{"href":"https:\/\/musee.oceano.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=25827"}],"wp:term":[{"taxonomy":"etatexpositions","embeddable":true,"href":"https:\/\/musee.oceano.org\/pt-pt\/wp-json\/wp\/v2\/etatexpositions?post=25827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}